{"id":99,"count":1,"description":"","link":"https:\/\/digitalwebzones.in\/blog\/category\/social-media\/","name":"Social Media","slug":"social-media","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/categories\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/posts?categories=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}