{"id":2,"count":1,"description":"","link":"https:\/\/digitalwebzones.in\/blog\/tag\/how-do-i-create-a-responsive-website-design\/","name":"How do I create a responsive website design","slug":"how-do-i-create-a-responsive-website-design","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/tags\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digitalwebzones.in\/blog\/wp-json\/wp\/v2\/posts?tags=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}